{"id":4051,"date":"2024-11-07T04:00:00","date_gmt":"2024-11-07T04:00:00","guid":{"rendered":"im-59810"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T00:00:00","slug":"veranderingen-in-de-kleineondernemersregeling-per-2025","status":"publish","type":"post","link":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/","title":{"rendered":"Veranderingen in de kleineondernemersregeling per 2025"},"content":{"rendered":"<p>De kleineondernemersregeling (KOR) houdt in, dat in Nederland gevestigde ondernemers gebruik kunnen maken van een vrijstelling van omzetbelasting, mits hun belaste jaaromzet niet meer dan &euro; 20.000 bedraagt. Ondernemers moeten vooraf melden dat zij de KOR willen toepassen. Toepassing van de KOR houdt in, dat ondernemers geen btw op hun facturen in rekening brengen en geen btw op kosten en investeringen in aftrek brengen. Vanaf 2025 kan een in Nederland gevestigde ondernemer de KOR door opzegging tussentijds be&euml;indigen. De KOR eindigt dan op de eerste dag van het volgende kalenderkwartaal, tenzij dat minder dan vier weken na ontvangst van de opzegging aanvangt. In dat geval eindigt de KOR een kalenderkwartaal later. Als de ondernemer de KOR opnieuw wil toepassen, kan dat pas in het tweede jaar na het jaar waarin de KOR is be&euml;indigd.<\/p>\n<h4>Voorwaarden KOR binnen de EU<\/h4>\n<p>Vanaf 1 januari 2025 kunnen ondernemers ook in andere lidstaten van de EU dan het land van vestiging gebruikmaken van de KOR. Toepassing van de Nederlandse KOR betekent niet automatisch toepassing van de KOR in een andere EU-lidstaat of andersom. Er moet worden voldaan aan de voorwaarden van de KOR-regeling van de betreffende EU-lidstaat. De lidstaten mogen de drempel voor de vrijstelling zelf vaststellen, maar maximaal op een omzet van &euro; 85.000. De lidstaten mogen verschillende omzetdrempels hanteren voor verschillende bedrijfssectoren. Voor toepassing van de KOR binnen de EU gelden de volgende voorwaarden:<br \/>\n&bull;&nbsp;&nbsp; &nbsp;de jaaromzet van de ondernemer in de EU bedraagt niet meer dan &euro; 100.000, en<br \/>\n&bull;&nbsp;&nbsp; &nbsp;de omzet in de lidstaat waar de ondernemer niet is gevestigd, is niet hoger dan de drempel die in die lidstaat van toepassing is.<\/p>\n<h4>Overgangsregeling<\/h4>\n<p>Nederlandse ondernemers kunnen tot en met 3 december 2024 aan de inspecteur melden dat zij de KOR per 1 januari 2025 in Nederland willen toepassen. Ondernemers, die de KOR al toepassen, hoeven geen melding te doen. De melding bevat ten minste de jaaromzet in Nederland tijdens het kalenderjaar 2024 tot het tijdstip waarop de melding wordt gedaan. De inspecteur kan bij voor bezwaar vatbare beschikking beslissen dat de ondernemer niet in aanmerking komt voor toepassing van de vrijstelling, als aannemelijk is dat niet zal worden voldaan aan de voorwaarden voor toepassing van de vrijstelling.<\/p>\n<div style=\"font-size:smaller\" class=\"im_source\">Bron:Overig | publicatie | 04-11-2024<\/div>\n","protected":false},"excerpt":{"rendered":"<p>De kleineondernemersregeling (KOR) houdt in, dat in Nederland gevestigde ondernemers gebruik kunnen maken van een vrijstelling van omzetbelasting, mits hun belaste jaaromzet niet meer dan &euro; 20.000 bedraagt. Ondernemers moeten vooraf melden dat<\/p>\n","protected":false},"author":1,"featured_media":4052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[],"class_list":["post-4051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eindejaarsactualiteiten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranderingen in de kleineondernemersregeling per 2025 - Fortius Accountants<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranderingen in de kleineondernemersregeling per 2025 - Fortius Accountants\" \/>\n<meta property=\"og:description\" content=\"De kleineondernemersregeling (KOR) houdt in, dat in Nederland gevestigde ondernemers gebruik kunnen maken van een vrijstelling van omzetbelasting, mits hun belaste jaaromzet niet meer dan &euro; 20.000 bedraagt. Ondernemers moeten vooraf melden dat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Fortius Accountants\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-07T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fortiusaccountants.nl\/wp-content\/uploads\/2024\/11\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/#\\\/schema\\\/person\\\/d2cee72f7386a5437d5355ae9231a5e5\"},\"headline\":\"Veranderingen in de kleineondernemersregeling per 2025\",\"datePublished\":\"2024-11-07T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/\"},\"wordCount\":377,\"image\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fortiusaccountants.nl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg\",\"articleSection\":[\"Eindejaarsactualiteiten\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/\",\"url\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/\",\"name\":\"Veranderingen in de kleineondernemersregeling per 2025 - Fortius Accountants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fortiusaccountants.nl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg\",\"datePublished\":\"2024-11-07T04:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/#\\\/schema\\\/person\\\/d2cee72f7386a5437d5355ae9231a5e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fortiusaccountants.nl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg\",\"contentUrl\":\"https:\\\/\\\/fortiusaccountants.nl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg\",\"width\":800,\"height\":536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/2024\\\/11\\\/07\\\/veranderingen-in-de-kleineondernemersregeling-per-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fortiusaccountants.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranderingen in de kleineondernemersregeling per 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/#website\",\"url\":\"https:\\\/\\\/fortiusaccountants.nl\\\/\",\"name\":\"Fortius Accountants\",\"description\":\"Persoonlijk betrokken\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fortiusaccountants.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fortiusaccountants.nl\\\/#\\\/schema\\\/person\\\/d2cee72f7386a5437d5355ae9231a5e5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25af659369b320d0607ceee04b139dcfca3d6c289f16e59caa0c7f5b3189d7a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25af659369b320d0607ceee04b139dcfca3d6c289f16e59caa0c7f5b3189d7a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25af659369b320d0607ceee04b139dcfca3d6c289f16e59caa0c7f5b3189d7a3?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/denharing.admits-it.nl\"],\"url\":\"https:\\\/\\\/fortiusaccountants.nl\\\/index.php\\\/author\\\/denharing_user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranderingen in de kleineondernemersregeling per 2025 - Fortius Accountants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/","og_locale":"nl_NL","og_type":"article","og_title":"Veranderingen in de kleineondernemersregeling per 2025 - Fortius Accountants","og_description":"De kleineondernemersregeling (KOR) houdt in, dat in Nederland gevestigde ondernemers gebruik kunnen maken van een vrijstelling van omzetbelasting, mits hun belaste jaaromzet niet meer dan &euro; 20.000 bedraagt. Ondernemers moeten vooraf melden dat","og_url":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/","og_site_name":"Fortius Accountants","article_published_time":"2024-11-07T04:00:00+00:00","og_image":[{"width":800,"height":536,"url":"https:\/\/fortiusaccountants.nl\/wp-content\/uploads\/2024\/11\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"admin","Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/#article","isPartOf":{"@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/"},"author":{"name":"admin","@id":"https:\/\/fortiusaccountants.nl\/#\/schema\/person\/d2cee72f7386a5437d5355ae9231a5e5"},"headline":"Veranderingen in de kleineondernemersregeling per 2025","datePublished":"2024-11-07T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/"},"wordCount":377,"image":{"@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/fortiusaccountants.nl\/wp-content\/uploads\/2024\/11\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg","articleSection":["Eindejaarsactualiteiten"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/","url":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/","name":"Veranderingen in de kleineondernemersregeling per 2025 - Fortius Accountants","isPartOf":{"@id":"https:\/\/fortiusaccountants.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/#primaryimage"},"image":{"@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/fortiusaccountants.nl\/wp-content\/uploads\/2024\/11\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg","datePublished":"2024-11-07T04:00:00+00:00","author":{"@id":"https:\/\/fortiusaccountants.nl\/#\/schema\/person\/d2cee72f7386a5437d5355ae9231a5e5"},"breadcrumb":{"@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/#primaryimage","url":"https:\/\/fortiusaccountants.nl\/wp-content\/uploads\/2024\/11\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg","contentUrl":"https:\/\/fortiusaccountants.nl\/wp-content\/uploads\/2024\/11\/64e52c76-0f69-484d-bac0-8d6269a0ca0e.jpg","width":800,"height":536},{"@type":"BreadcrumbList","@id":"https:\/\/fortiusaccountants.nl\/index.php\/2024\/11\/07\/veranderingen-in-de-kleineondernemersregeling-per-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fortiusaccountants.nl\/"},{"@type":"ListItem","position":2,"name":"Veranderingen in de kleineondernemersregeling per 2025"}]},{"@type":"WebSite","@id":"https:\/\/fortiusaccountants.nl\/#website","url":"https:\/\/fortiusaccountants.nl\/","name":"Fortius Accountants","description":"Persoonlijk betrokken","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fortiusaccountants.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/fortiusaccountants.nl\/#\/schema\/person\/d2cee72f7386a5437d5355ae9231a5e5","name":"admin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/25af659369b320d0607ceee04b139dcfca3d6c289f16e59caa0c7f5b3189d7a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25af659369b320d0607ceee04b139dcfca3d6c289f16e59caa0c7f5b3189d7a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25af659369b320d0607ceee04b139dcfca3d6c289f16e59caa0c7f5b3189d7a3?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/denharing.admits-it.nl"],"url":"https:\/\/fortiusaccountants.nl\/index.php\/author\/denharing_user\/"}]}},"_links":{"self":[{"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/posts\/4051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/comments?post=4051"}],"version-history":[{"count":0,"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/posts\/4051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/media\/4052"}],"wp:attachment":[{"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/media?parent=4051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/categories?post=4051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fortiusaccountants.nl\/index.php\/wp-json\/wp\/v2\/tags?post=4051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}